{"id":4303,"date":"2020-08-26T11:13:26","date_gmt":"2020-08-26T11:13:26","guid":{"rendered":"https:\/\/www.info.valladolid.es\/blog\/?p=4303"},"modified":"2020-10-27T11:18:44","modified_gmt":"2020-10-27T11:18:44","slug":"sanson-norte-de-castilla","status":"publish","type":"post","link":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/","title":{"rendered":"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En septiembre de 1995 El Norte de Castilla comenz\u00f3 a publicar una vi\u00f1eta diaria de Sans\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces, sin interrupci\u00f3n, el diario decano de la prensa espa\u00f1ola ha ofrecido a sus lectores los chistes, dibujos y vi\u00f1etas de Rafael Vega que han atendido y analizado con su mirada cr\u00edtica y mordaz durante estos veinticinco a\u00f1os no solo los acontecimientos m\u00e1s sobresalientes que han definido nuestra historia inmediata, sino los detalles costumbristas que<br>perfilan nuestra vida cotidiana y nuestra identidad. Desde lo local hasta lo universal, los 10.000 dibujos, tiras y vi\u00f1etas publicados por Sans\u00f3n en El Norte de Castilla y en los diarios regionales de Vocento constituyen una elocuente referencia para echar la vista sobre nuestro \u00faltimo cuarto de siglo y analizar de d\u00f3nde venimos para, acaso, intuir d\u00f3nde estamos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con motivo de este especial aniversario, El Ayuntamiento de Valladolid acoge en su sala de Las Francesas la exposici\u00f3n \u2018Sans\u00f3n 25 a\u00f1os en El Norte de Castilla. Una antolog\u00eda caprichosa entre 1995 y 2020\u2019 que re\u00fane una amplia y variada muestra de las vi\u00f1etas, tiras y dibujos publicados<br>durante este \u00faltimo cuarto de siglo; un grato y resumido paseo por nuestros m\u00e1s inmediatos recuerdos locales, regionales y nacionales para recordar c\u00f3mo \u00e9ramos a finales del siglo XX para ser y pensar como pensamos en este bien entrado siglo XXI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n, que se inaugura el jueves, 3 de septiembre y que permanecer\u00e1 en la sala de Las Francesas hasta el 2 de noviembre de 2020, dedicar\u00e1 tambi\u00e9n una secci\u00f3n a las vi\u00f1etas que el autor ha venido publicando en El Norte de Castilla y en los diarios regionales de Vocento,<br>desde que se inici\u00f3 la pandemia de la covid-19 hasta el fin del estado de alarma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Sobre Sans\u00f3n<\/u><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rafael\nVega, (1967), se licenci\u00f3 en la Facultad de Filosof\u00eda y Letras de Valladolid y\nse especializ\u00f3 en Historia Medieval antes de dedicarse al periodismo y la\nedici\u00f3n. A su empe\u00f1o diario como colaborador period\u00edstico a\u00f1ade su actividad\nprofesional como editor de prensa y literario en varios sellos editoriales y\nuna labor art\u00edstica que aflora cada cierto tiempo en muestras y exposiciones,\ncomo la mostrada en el a\u00f1os 2018 en la \u2018Sala 0\u2019 del Museo Patio Herreriano de\nValladolid bajo el t\u00edtulo de \u2018ProLogos\u2019, o su muestra \u2018Cardumen\u2019 en el Museo\nFoz C\u00f4a de Portugal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque en 1995 sus vi\u00f1etas iniciaron su andadura en El Norte de Castilla cobijadas en sus p\u00e1ginas de informaci\u00f3n local, pronto dieron el salto a la secci\u00f3n de Castilla y Le\u00f3n, hasta que en el a\u00f1o 2005 se aloj\u00f3 en las p\u00e1ginas de Opini\u00f3n. Para evitar que su atenci\u00f3n a la actualidad pol\u00edtica y social de \u00e1mbito m\u00e1s general privara a los lectores de su impronta local y auton\u00f3mica, la direcci\u00f3n del peri\u00f3dico decidi\u00f3 que simultaneara su aparici\u00f3n diaria en las p\u00e1ginas de Opini\u00f3n con la publicaci\u00f3n de una tira dedicada al \u00e1mbito local y regional todos los domingos, tira que actualmente comparte la p\u00e1gina 2 con el art\u00edculo dominical del director, \u00c1ngel Ortiz D\u00e1vila.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el a\u00f1o 2006, Sans\u00f3n fue galardonado con el Premio de Periodismo &#8216;Francisco de Coss\u00edo&#8217; en la modalidad de humor gr\u00e1fico y ha publicado hasta la fecha dos libros recopilatorios que se a\u00f1aden al que edita El Norte de Castilla con motivo del 25 aniversario, junto con la exposici\u00f3n antol\u00f3gica patrocinada por el Ayuntamiento de Valladolid, la Diputaci\u00f3n de Valladolid y con la colaboraci\u00f3n de la Junta de Castilla y Le\u00f3n.<\/p>\n\n\n\n<div aria-live=\"polite\" id=\"soliloquy-container-4314_1\" class=\"soliloquy-container soliloquy-transition-fade  soliloquy-theme-base\" style=\"max-width:900px;max-height:520px;\"><ul id=\"soliloquy-4314_1\" class=\"soliloquy-slider soliloquy-slides soliloquy-wrap soliloquy-clear\"><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-1 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4315\" class=\"soliloquy-image soliloquy-image-1\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-25-a\u00f1os-1.jpg\" alt=\"sanson 25 a\u00f1os 1\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-2 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4316\" class=\"soliloquy-image soliloquy-image-2\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-25-a\u00f1os-2.jpg\" alt=\"sanson 25 a\u00f1os 2\" \/><\/li><\/ul><\/div><noscript><style type=\"text\/css\">#soliloquy-container-4314_1{opacity:1}<\/style><\/noscript>\n\n\n\n<pre class=\"wp-block-preformatted\"><\/pre>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A lo largo de las pr\u00f3ximas p\u00e1ginas, Rafa Vega, \u2018Sans\u00f3n\u2019, resume en una selecci\u00f3n de vi\u00f1etas y tiras de humor un cuarto de siglo en las p\u00e1ginas de El Norte de Castilla y, desde 2009, del resto de cabeceras regionales de Vocento. Se trata de una proeza al alcance de muy pocos. Rafa es un creador dotado de un talento fuera de lo com\u00fan. Es un observador impenitente, selectivo, agudo y audaz de las peque\u00f1as y las grandes historias del d\u00eda a d\u00eda. Est\u00e1 pertrechado de inmensa cultura y sentido com\u00fan. Es adem\u00e1s lo suficientemente sacrificado y generoso como para someter su vida personal, y la de su familia, al r\u00edgido calendario que exige la publicaci\u00f3n diaria de una ilustraci\u00f3n que concentre en un solo impacto de lectura la iron\u00eda, la sonrisa, la opini\u00f3n, la paradoja, la novedad, la cr\u00edtica y el justo punto de acidez&#8230; Ingenio en estado puro.<br>&nbsp;<br>Es ya una obligaci\u00f3n para El Norte de Castilla salir cada ma\u00f1ana a los quioscos con las \u2018ingenialidades\u2019 de Sans\u00f3n. Gracias a ellas somos un peri\u00f3dico mejor, m\u00e1s exclusivo, m\u00e1s cercano y entretenido. El valioso libro que tiene en sus manos demuestra la enorme riqueza que aporta una firma como la suya, al modo de una especie de lluvia fina que va conformando un relato colectivo, en presente continuo, pero tambi\u00e9n la personalidad de la cabecera bajo la que se publica. Hoy El Norte de Castilla es lo que es tambi\u00e9n, de manera singular, gracias a los dibujos de Sans\u00f3n: nos une ser universales, perseguir la excelencia, mantenernos atentos, vigentes y vigilantes. Y que disfrutamos del dif\u00edcil trabajo de contar la actualidad a una opini\u00f3n p\u00fablica cada vez m\u00e1s exigente.<br>&nbsp;<br>Las casi 400 piezas de este volumen no solo miran y valoran las noticias de cada momento, sino tambi\u00e9n la vida cotidiana y nuestra realidad social en este \u00faltimo cuarto de siglo. Son un tesoro. Son un regalo. Son el resultado de un desaf\u00edo siempre inacabado. Son un privilegio.<br>&nbsp; <\/p><cite>\u00c1ngel Ortiz D\u00e1vila, director de El Norte de Castilla. Pr\u00f3logo al libro &#8216;Sans\u00f3n. 25 a\u00f1os.Antolog\u00eda caprichosa entre 1995 y 2020.<br><\/cite><\/blockquote>\n\n\n\n<div aria-live=\"polite\" id=\"soliloquy-container-4318_2\" class=\"soliloquy-container soliloquy-transition-fade  soliloquy-theme-base\" style=\"max-width:780px;max-height:500px;\"><ul id=\"soliloquy-4318_2\" class=\"soliloquy-slider soliloquy-slides soliloquy-wrap soliloquy-clear\"><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-1 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4319\" class=\"soliloquy-image soliloquy-image-1\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-1-780x500_c.jpg\" alt=\"sanson 1\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-2 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4320\" class=\"soliloquy-image soliloquy-image-2\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-2-780x500_c.jpg\" alt=\"sanson 2\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-3 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4321\" class=\"soliloquy-image soliloquy-image-3\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-3-780x500_c.jpg\" alt=\"sanson 3\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-4 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4322\" class=\"soliloquy-image soliloquy-image-4\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-4-780x500_c.jpg\" alt=\"sanson 4\" \/><\/li><\/ul><\/div><noscript><style type=\"text\/css\">#soliloquy-container-4318_2{opacity:1}<\/style><\/noscript>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Desde que lo conozco, siempre le he o\u00eddo decir que, en realidad, su trabajo no es dibujar vi\u00f1etas, que \u00e9l se dedica a desactivar bombas y ha de conseguirlo antes de que el  temporizador se agote y el explosivo reviente el d\u00eda. La parte buena es que siempre lo  consigue, lo que hace de \u00e9l una especie de TEDAX zurdo y milagroso que siempre corta el cable<br> adecuado. Hay parte mala: se trata de una bomba m\u00e1gica y la cuenta atr\u00e1s vuelve a ponerse  en marcha en el momento exacto de su desactivaci\u00f3n. Lejos de lamentarme, me temo que eso  es algo que nunca hemos sabido agradecer lo suficiente, porque sin bomba no hay miedo, sin  miedo no llegan las musas y sin musas no tenemos vi\u00f1eta de Sans\u00f3n.<br> Y sin su vi\u00f1eta quiz\u00e1 no exista ni la ma\u00f1ana misma.<br> En ese caso tendr\u00edamos que mirar la vida directamente a la cara, sin filtros, y ya sabemos que  eso ciega. Nos iba a tocar pintar bigotes a la realidad para hacerla m\u00e1s digerible, m\u00e1s brillante  y m\u00e1s bella. Una realidad m\u00e1s Sans\u00f3n. Estoy pensando que quiz\u00e1 deber\u00edamos manipular la  bomba para que se reinicie dos veces al d\u00eda. Sospecho que, con el doble de dosis de Rafa, quiz\u00e1  tendr\u00edamos la mitad de problemas.<\/p><cite>Jos\u00e9 F. Pel\u00e1ez. Columnista de El Norte de Castilla<\/cite><\/blockquote>\n\n\n\n<div aria-live=\"polite\" id=\"soliloquy-container-4324_3\" class=\"soliloquy-container soliloquy-transition-fade  soliloquy-theme-base\" style=\"max-width:800px;max-height:500px;\"><ul id=\"soliloquy-4324_3\" class=\"soliloquy-slider soliloquy-slides soliloquy-wrap soliloquy-clear\"><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-1 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4325\" class=\"soliloquy-image soliloquy-image-1\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-5-800x500_c.jpg\" alt=\"sanson 5\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-2 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4326\" class=\"soliloquy-image soliloquy-image-2\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-6-800x500_c.jpg\" alt=\"sanson 6\" \/><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-3 soliloquy-image-slide\" draggable=\"false\" style=\"list-style:none\"><img decoding=\"async\" id=\"soliloquy-image-4327\" class=\"soliloquy-image soliloquy-image-3\" src=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/09\/sanson-7-800x500_c.jpg\" alt=\"sanson 7\" \/><\/li><\/ul><\/div><noscript><style type=\"text\/css\">#soliloquy-container-4324_3{opacity:1}<\/style><\/noscript>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Si antes de hacerse carne y habitar entre nosotros el Verbo hubiese preguntado, Sans\u00f3n habr\u00eda  contestado alzando las cejas \u201cno te molestes, ya vamos nosotros\u201d; porque en el universo de  Sans\u00f3n es la carne la que se hace palabra despojando la realidad de todo lo dem\u00e1s, en un<br> alarde radical de ese principio del dibujo humor\u00edstico seg\u00fan el cu\u00e1l todo lo que no es esencial  en una vi\u00f1eta sobra.<br> Y no es esencial en el universo de Rafa Vega \u201cSans\u00f3n\u201d, que cumple ahora 25 a\u00f1os en las  p\u00e1ginas de El Norte, ni el entorno en que te encuentras, ni lo que est\u00e1s haciendo, ni lo que  pasa a tu alrededor, ni siquiera lo que piensas o sientes. En sus dibujos apenas est\u00e1n  esbozados paisajes, arquitecturas o muebles; a sus personajes no les suceden cosas, pero<br> tampoco son simples bustos pensantes que sirvan de soporte para colocarnos una reflexi\u00f3n  m\u00e1s o menos atinada o ingeniosa sobre la actualidad, como tan a menudo pasa con el humor  gr\u00e1fico de prensa. Nada de eso es importante en las vi\u00f1etas de Sans\u00f3n. Si me apuran, ni<br> siquiera las noticias a las que se refieren las vi\u00f1etas son lo que realmente interesa al autor.<br> En los chistes de mi amigo Rafa hay un \u00fanico af\u00e1n, aunque m\u00e1s que una ambici\u00f3n es una luz  ardiente que brilla como el tesoro de un drag\u00f3n. La luz de una verdad profunda y valios\u00edsima.<br> Sans\u00f3n nos ofrece cada d\u00eda en su vi\u00f1eta la esencia de lo que nos hace humanos: un personaje  habla a otro que le escucha. El otro personaje responde o reacciona; las m\u00e1s de las veces  simplemente se sorprende de lo que oye y se compadece, lo que provoca la empat\u00eda del lector.<br> As\u00ed que cada vi\u00f1eta es una epifan\u00eda cotidiana del di\u00e1logo, de la comprensi\u00f3n y de la piedad.<br> Todo en las vi\u00f1etas de Sans\u00f3n subraya esta \u201capoteosis diaria\u201d de la comunicaci\u00f3n personal: el  rabillo de los bocadillos, que indica qui\u00e9n habla, no est\u00e1 resuelto con un simple triangulito que  apunte a cada emisor, sino que se extiende, serpentea y hasta envuelve a los personajes<br> haci\u00e9ndose due\u00f1o de la escena. Sus caricaturas siempre se presentan opuestas, de perfil y en  el mismo plano, con una composici\u00f3n cl\u00e1sica en la que nada nos distrae del protagonismo de la relaci\u00f3n de dos personajes que se miran.<br> Sans\u00f3n combina esta disciplina compositiva con un grafismo torturado y abrupto que con el  paso de los a\u00f1os ha ido perdiendo agresividad, y es que la c\u00e1lida humanidad de Rafa se ha  impuesto de tal manera a la voluntad de estilo que sus personajes picassianos, con boca  vertical y nuca picuda, resultan adorables. Es lo que tiene respetar al lector, estar siempre de  parte de los d\u00e9biles, ser sabio y humilde y trabajar a la luz de una verdad profunda: somos  seres que se hablan y se escuchan.<\/p><cite>J.M.Nieto. Humorista gr\u00e1fico<\/cite><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>En septiembre de 1995 El Norte de Castilla comenz\u00f3 a publicar una vi\u00f1eta diaria de Sans\u00f3n. Desde entonces, sin interrupci\u00f3n, el diario decano de la prensa espa\u00f1ola ha ofrecido a sus lectores los chistes, dibujos y vi\u00f1etas de Rafael Vega que han atendido y analizado con su mirada cr\u00edtica y mordaz durante estos veinticinco a\u00f1os no solo los acontecimientos m\u00e1s sobresalientes que han definido nuestra historia inmediata, sino los detalles costumbristas queperfilan nuestra vida cotidiana y nuestra identidad. Desde lo local hasta lo universal, los 10.000 dibujos, tiras y vi\u00f1etas publicados por Sans\u00f3n en El Norte de Castilla y en los diarios regionales de Vocento constituyen una elocuente referencia para echar la vista sobre nuestro \u00faltimo cuarto de siglo y analizar de d\u00f3nde venimos para, acaso, intuir d\u00f3nde estamos. Con motivo de este especial aniversario, El Ayuntamiento de Valladolid acoge en su sala de Las Francesas la exposici\u00f3n \u2018Sans\u00f3n 25 a\u00f1os en El Norte de Castilla. Una antolog\u00eda caprichosa entre 1995 y 2020\u2019 que re\u00fane una amplia y variada muestra de las vi\u00f1etas, tiras y dibujos publicadosdurante este \u00faltimo cuarto de siglo; un grato y resumido paseo por nuestros m\u00e1s inmediatos recuerdos locales, regionales y nacionales para recordar c\u00f3mo \u00e9ramos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-4303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-museos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla - Blog Cultura y Turismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla - Blog Cultura y Turismo\" \/>\n<meta property=\"og:description\" content=\"En septiembre de 1995 El Norte de Castilla comenz\u00f3 a publicar una vi\u00f1eta diaria de Sans\u00f3n. Desde entonces, sin interrupci\u00f3n, el diario decano de la prensa espa\u00f1ola ha ofrecido a sus lectores los chistes, dibujos y vi\u00f1etas de Rafael Vega que han atendido y analizado con su mirada cr\u00edtica y mordaz durante estos veinticinco a\u00f1os no solo los acontecimientos m\u00e1s sobresalientes que han definido nuestra historia inmediata, sino los detalles costumbristas queperfilan nuestra vida cotidiana y nuestra identidad. Desde lo local hasta lo universal, los 10.000 dibujos, tiras y vi\u00f1etas publicados por Sans\u00f3n en El Norte de Castilla y en los diarios regionales de Vocento constituyen una elocuente referencia para echar la vista sobre nuestro \u00faltimo cuarto de siglo y analizar de d\u00f3nde venimos para, acaso, intuir d\u00f3nde estamos. Con motivo de este especial aniversario, El Ayuntamiento de Valladolid acoge en su sala de Las Francesas la exposici\u00f3n \u2018Sans\u00f3n 25 a\u00f1os en El Norte de Castilla. Una antolog\u00eda caprichosa entre 1995 y 2020\u2019 que re\u00fane una amplia y variada muestra de las vi\u00f1etas, tiras y dibujos publicadosdurante este \u00faltimo cuarto de siglo; un grato y resumido paseo por nuestros m\u00e1s inmediatos recuerdos locales, regionales y nacionales para recordar c\u00f3mo \u00e9ramos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultura y Turismo\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-26T11:13:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-27T11:18:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/08\/portada-sanson.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/\"},\"author\":{\"name\":\"administrador\",\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/#\\\/schema\\\/person\\\/845cac97e6156a5a9c5abd68b7b9a5d5\"},\"headline\":\"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla\",\"datePublished\":\"2020-08-26T11:13:26+00:00\",\"dateModified\":\"2020-10-27T11:18:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/\"},\"wordCount\":1787,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/portada-sanson.jpg\",\"articleSection\":[\"Arte y Museos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/\",\"url\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/\",\"name\":\"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla - Blog Cultura y Turismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/portada-sanson.jpg\",\"datePublished\":\"2020-08-26T11:13:26+00:00\",\"dateModified\":\"2020-10-27T11:18:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/#\\\/schema\\\/person\\\/845cac97e6156a5a9c5abd68b7b9a5d5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/portada-sanson.jpg\",\"contentUrl\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/portada-sanson.jpg\",\"width\":750,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/sanson-norte-de-castilla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/\",\"name\":\"Blog Cultura y Turismo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/#\\\/schema\\\/person\\\/845cac97e6156a5a9c5abd68b7b9a5d5\",\"name\":\"administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/418161d2f95196597e2d305bd301c850afab7f4b284a344fb2d759f048b71c61?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/418161d2f95196597e2d305bd301c850afab7f4b284a344fb2d759f048b71c61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/418161d2f95196597e2d305bd301c850afab7f4b284a344fb2d759f048b71c61?s=96&d=mm&r=g\",\"caption\":\"administrador\"},\"url\":\"https:\\\/\\\/www.info.valladolid.es\\\/blog\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla - Blog Cultura y Turismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/","og_locale":"es_ES","og_type":"article","og_title":"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla - Blog Cultura y Turismo","og_description":"En septiembre de 1995 El Norte de Castilla comenz\u00f3 a publicar una vi\u00f1eta diaria de Sans\u00f3n. Desde entonces, sin interrupci\u00f3n, el diario decano de la prensa espa\u00f1ola ha ofrecido a sus lectores los chistes, dibujos y vi\u00f1etas de Rafael Vega que han atendido y analizado con su mirada cr\u00edtica y mordaz durante estos veinticinco a\u00f1os no solo los acontecimientos m\u00e1s sobresalientes que han definido nuestra historia inmediata, sino los detalles costumbristas queperfilan nuestra vida cotidiana y nuestra identidad. Desde lo local hasta lo universal, los 10.000 dibujos, tiras y vi\u00f1etas publicados por Sans\u00f3n en El Norte de Castilla y en los diarios regionales de Vocento constituyen una elocuente referencia para echar la vista sobre nuestro \u00faltimo cuarto de siglo y analizar de d\u00f3nde venimos para, acaso, intuir d\u00f3nde estamos. Con motivo de este especial aniversario, El Ayuntamiento de Valladolid acoge en su sala de Las Francesas la exposici\u00f3n \u2018Sans\u00f3n 25 a\u00f1os en El Norte de Castilla. Una antolog\u00eda caprichosa entre 1995 y 2020\u2019 que re\u00fane una amplia y variada muestra de las vi\u00f1etas, tiras y dibujos publicadosdurante este \u00faltimo cuarto de siglo; un grato y resumido paseo por nuestros m\u00e1s inmediatos recuerdos locales, regionales y nacionales para recordar c\u00f3mo \u00e9ramos [&hellip;]","og_url":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/","og_site_name":"Blog Cultura y Turismo","article_published_time":"2020-08-26T11:13:26+00:00","article_modified_time":"2020-10-27T11:18:44+00:00","og_image":[{"width":750,"height":460,"url":"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/08\/portada-sanson.jpg","type":"image\/jpeg"}],"author":"administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"administrador","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#article","isPartOf":{"@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/"},"author":{"name":"administrador","@id":"https:\/\/www.info.valladolid.es\/blog\/#\/schema\/person\/845cac97e6156a5a9c5abd68b7b9a5d5"},"headline":"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla","datePublished":"2020-08-26T11:13:26+00:00","dateModified":"2020-10-27T11:18:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/"},"wordCount":1787,"commentCount":0,"image":{"@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/08\/portada-sanson.jpg","articleSection":["Arte y Museos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/","url":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/","name":"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla - Blog Cultura y Turismo","isPartOf":{"@id":"https:\/\/www.info.valladolid.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#primaryimage"},"image":{"@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/08\/portada-sanson.jpg","datePublished":"2020-08-26T11:13:26+00:00","dateModified":"2020-10-27T11:18:44+00:00","author":{"@id":"https:\/\/www.info.valladolid.es\/blog\/#\/schema\/person\/845cac97e6156a5a9c5abd68b7b9a5d5"},"breadcrumb":{"@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#primaryimage","url":"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/08\/portada-sanson.jpg","contentUrl":"https:\/\/www.info.valladolid.es\/blog\/wp-content\/uploads\/2020\/08\/portada-sanson.jpg","width":750,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.info.valladolid.es\/blog\/sanson-norte-de-castilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.info.valladolid.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Sans\u00f3n. 25 a\u00f1os en El Norte de Castilla"}]},{"@type":"WebSite","@id":"https:\/\/www.info.valladolid.es\/blog\/#website","url":"https:\/\/www.info.valladolid.es\/blog\/","name":"Blog Cultura y Turismo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.info.valladolid.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.info.valladolid.es\/blog\/#\/schema\/person\/845cac97e6156a5a9c5abd68b7b9a5d5","name":"administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/418161d2f95196597e2d305bd301c850afab7f4b284a344fb2d759f048b71c61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/418161d2f95196597e2d305bd301c850afab7f4b284a344fb2d759f048b71c61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/418161d2f95196597e2d305bd301c850afab7f4b284a344fb2d759f048b71c61?s=96&d=mm&r=g","caption":"administrador"},"url":"https:\/\/www.info.valladolid.es\/blog\/author\/administrador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/posts\/4303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/comments?post=4303"}],"version-history":[{"count":6,"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/posts\/4303\/revisions"}],"predecessor-version":[{"id":4328,"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/posts\/4303\/revisions\/4328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/media\/4329"}],"wp:attachment":[{"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/media?parent=4303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/categories?post=4303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.info.valladolid.es\/blog\/wp-json\/wp\/v2\/tags?post=4303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}